{"id":71764,"date":"2024-03-22T23:03:23","date_gmt":"2024-03-22T22:03:23","guid":{"rendered":"https:\/\/abinox-chr-clim.com\/index.php\/product\/balai-avec-ramasse-poussiere-jantex\/"},"modified":"2026-08-31T13:55:11","modified_gmt":"2026-08-31T11:55:11","slug":"balai-avec-ramasse-poussiere-jantex","status":"publish","type":"product","link":"https:\/\/abinox-chr-clim.com\/index.php\/product\/balai-avec-ramasse-poussiere-jantex\/","title":{"rendered":"Balai avec ramasse-poussi\u00e8re Jantex"},"content":{"rendered":"<p>Traitez rapidement toutes les t\u00e2ches de balayage urgentes dans les zones commerciales. Un manche plus long vous \u00e9vite de vous pencher et \u00e9vite les tensions inutiles au dos. Le couvercle coupe-vent de la pelle \u00e0 poussi\u00e8re emp\u00eache le contenu de tomber et \u00e9vite un surplus de travail. Le support maintient la pelle \u00e0 poussi\u00e8re attach\u00e9e au balai pour un rangement s\u00fbr et optimis\u00e9. Conception robuste en polypropyl\u00e8ne pour une fiabilit\u00e9 durable.  Traitez rapidement toutes les t\u00e2ches de balayage urgentes dans les zones commerciales.<\/p>\n<p>Caract\u00e9ristiques :<br \/> Dimensions : 850(H) x 160(L) x 30(P) mm.<br \/> Mati\u00e8re : Polypropyl\u00e8ne<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Balai avec ramasse-poussi\u00e8re Jantex<\/p>\n","protected":false},"featured_media":81341,"comment_status":"closed","ping_status":"closed","template":"","meta":{"rs_blank_template":"","rs_page_bg_color":"","slide_template_v7":""},"product_brand":[],"product_cat":[1229,1227,1297,1216],"product_tag":[],"class_list":["post-71764","product","type-product","status-publish","has-post-thumbnail","product_cat-balais-et-brosses","product_cat-nettoyage","product_cat-non-palettisable","product_cat-usage-unique-et-entretien","first","instock","featured","taxable","shipping-taxable","purchasable","product-type-simple"],"_links":{"self":[{"href":"https:\/\/abinox-chr-clim.com\/index.php\/wp-json\/wp\/v2\/product\/71764","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/abinox-chr-clim.com\/index.php\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/abinox-chr-clim.com\/index.php\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/abinox-chr-clim.com\/index.php\/wp-json\/wp\/v2\/comments?post=71764"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/abinox-chr-clim.com\/index.php\/wp-json\/wp\/v2\/media\/81341"}],"wp:attachment":[{"href":"https:\/\/abinox-chr-clim.com\/index.php\/wp-json\/wp\/v2\/media?parent=71764"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/abinox-chr-clim.com\/index.php\/wp-json\/wp\/v2\/product_brand?post=71764"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/abinox-chr-clim.com\/index.php\/wp-json\/wp\/v2\/product_cat?post=71764"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/abinox-chr-clim.com\/index.php\/wp-json\/wp\/v2\/product_tag?post=71764"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}