{"id":71201,"date":"2024-03-22T19:40:21","date_gmt":"2024-03-22T18:40:21","guid":{"rendered":"https:\/\/abinox-chr-clim.com\/index.php\/product\/plateau-en-polyester-versalite-cambro-moka-mouchete-457-cm\/"},"modified":"2026-06-14T14:13:29","modified_gmt":"2026-06-14T12:13:29","slug":"plateau-en-polyester-versalite-cambro-moka-mouchete-457-cm","status":"publish","type":"product","link":"https:\/\/abinox-chr-clim.com\/index.php\/product\/plateau-en-polyester-versalite-cambro-moka-mouchete-457-cm\/","title":{"rendered":"Plateau en polyester Versalite Cambro moka mouchet\u00e9 45,7 cm"},"content":{"rendered":"<p>Plateaux empilables en polyester avec coins renforc\u00e9s et bords prot\u00e9g\u00e9s. Les bossages permettent \u00e0 l&rsquo;air de circuler pour un s\u00e9chage rapide. R\u00e9sistants \u00e0 la chaleur jusqu&rsquo;\u00e0 103\u00b0C et au lave-vaisselle.<br \/>Les coins en polyester renforc\u00e9 offrent une meilleure protection des angles et des bords contre les impacts.Les plots d&#8217;empilage permettent \u00e0 l&rsquo;air de circuler pour un s\u00e9chage rapide et des piles bien droites.Compatible lave-vaisselle &#8211; jusqu&rsquo;\u00e0 3 lavages par jour. Coloris \u00e9l\u00e9gant moka mouchet\u00e9. Construction robuste emp\u00eachant la flexion lors du transport d&rsquo;objets lourds. R\u00e9sistance thermique de -40\u00b0C \u00e0 130\u00b0C. Vendu \u00e0 l&rsquo;unit\u00e9.Les coins en polyester renforc\u00e9 offrent une meilleure protection des angles et des bords contre les impacts. .<br \/> Caract\u00e9ristiques :<br \/> Dimensions : 460(L) x 360(P) mm.<br \/> Mati\u00e8re : Polyester.<br \/> Temp\u00e9rature : -40 \u00b0C \u00e0 103 \u00b0C.<br \/> Couleur : Mouchet\u00e9 moka.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Plateau en polyester Versalite Cambro moka mouchet\u00e9 45,7 cm<\/p>\n","protected":false},"featured_media":90015,"comment_status":"closed","ping_status":"closed","template":"","meta":[],"product_brand":[],"product_cat":[1129,1297,1127,1106],"product_tag":[],"class_list":["post-71201","product","type-product","status-publish","has-post-thumbnail","product_cat-cambro","product_cat-non-palettisable","product_cat-plateaux-de-service","product_cat-restaurant-bar-et-hotel","product_shipping_class-free-shipping","first","outofstock","featured","taxable","shipping-taxable","purchasable","product-type-simple"],"_links":{"self":[{"href":"https:\/\/abinox-chr-clim.com\/index.php\/wp-json\/wp\/v2\/product\/71201","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/abinox-chr-clim.com\/index.php\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/abinox-chr-clim.com\/index.php\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/abinox-chr-clim.com\/index.php\/wp-json\/wp\/v2\/comments?post=71201"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/abinox-chr-clim.com\/index.php\/wp-json\/wp\/v2\/media\/90015"}],"wp:attachment":[{"href":"https:\/\/abinox-chr-clim.com\/index.php\/wp-json\/wp\/v2\/media?parent=71201"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/abinox-chr-clim.com\/index.php\/wp-json\/wp\/v2\/product_brand?post=71201"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/abinox-chr-clim.com\/index.php\/wp-json\/wp\/v2\/product_cat?post=71201"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/abinox-chr-clim.com\/index.php\/wp-json\/wp\/v2\/product_tag?post=71201"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}