{"id":110559,"date":"2025-05-29T11:58:35","date_gmt":"2025-05-29T09:58:35","guid":{"rendered":"https:\/\/abinox-chr-clim.com\/index.php\/product\/pots-a-frites-churchill-super-vitrified-nourish-andorra-green-290ml-lot-de-12\/"},"modified":"2026-06-14T15:00:52","modified_gmt":"2026-06-14T13:00:52","slug":"pots-a-frites-churchill-super-vitrified-nourish-andorra-green-290ml-lot-de-12","status":"publish","type":"product","link":"https:\/\/abinox-chr-clim.com\/index.php\/product\/pots-a-frites-churchill-super-vitrified-nourish-andorra-green-290ml-lot-de-12\/","title":{"rendered":"Pots \u00e0 frites Churchill Super Vitrified Nourish Andorra Green 290ml (Lot de 12)"},"content":{"rendered":"<p>La collection Nourish de Churchill est l&rsquo;accompagnement parfait pour des plats frais et locaux du monde entier. Fini dans une couleur Andorra Green, ces tasses \u00e0 frites Nourish compl\u00e8tent \u00e0 la fois les repas d\u00e9contract\u00e9s et raffin\u00e9s.Fabriqu\u00e9es avec un corps super vitrifi\u00e9, les tasses r\u00e9sistent \u00e0 l&rsquo;absorption d&rsquo;humidit\u00e9 et offrent une excellente r\u00e9tention de chaleur. Leur impressionnante r\u00e9sistance aux chocs thermiques minimise les bris et assure une solidit\u00e9 durable.Prot\u00e9g\u00e9es par l&rsquo;Eco Glaze de Churchill, ces tasses \u00e0 frites ont une excellente r\u00e9sistance aux taches et aux marques m\u00e9talliques et une durabilit\u00e9 accrue. Les tasses pr\u00e9sentent \u00e9galement un bord de rebord d\u00e9fini et un pied enti\u00e8rement \u00e9maill\u00e9 qui pr\u00e9vient les rayures lors de l&#8217;empilage.En plus de leur robustesse, les tasses \u00e0 frites Nourish offrent une commodit\u00e9 quotidienne. Elles sont adapt\u00e9es au micro-ondes et au lave-vaisselle, permettant un chauffage facile et un nettoyage sans effort.<\/p>\n<p>\u2022 Le corps super vitrifi\u00e9 n&rsquo;absorbe pas l&rsquo;humidit\u00e9 et poss\u00e8de des propri\u00e9t\u00e9s de r\u00e9tention de chaleur \u00e9lev\u00e9es<br \/>\u2022 La haute r\u00e9sistance aux chocs thermiques permet de r\u00e9duire les casses<br \/>\u2022 Finition \u00e9maill\u00e9e sup\u00e9rieure pour une r\u00e9sistance aux taches et aux marques m\u00e9talliques<br \/>\u2022 La base enti\u00e8rement vitr\u00e9e \u00e9vite les rayures lors de l&#8217;empilage<br \/>\u2022 Passe au micro-ondes et au lave-vaisselle<\/p>\n<p><b><u>Caract\u00e9ristiques du produit :<\/u><\/b><br \/>\u2022 Lot : 12.0<br \/>\u2022 Capacit\u00e9 : 290 ml<br \/>\u2022 Mati\u00e8re : Porcelaine super vitrifi\u00e9e<br \/>\u2022 Poids : 3,343 kg<br \/>\u2022 Couleur : Vert.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>100(\u00d8)mm. 290ml. Vert Andorra. Quantit\u00e9 par paquet\u00a0:\u00a012<\/p>\n","protected":false},"featured_media":105661,"comment_status":"open","ping_status":"closed","template":"","meta":[],"product_brand":[],"product_cat":[1023,1045,1297,1043],"product_tag":[],"class_list":["post-110559","product","type-product","status-publish","has-post-thumbnail","product_cat-art-de-la-table","product_cat-divers-vaisselle","product_cat-non-palettisable","product_cat-vaisselle","product_shipping_class-free-shipping","first","outofstock","featured","taxable","shipping-taxable","purchasable","product-type-simple"],"_links":{"self":[{"href":"https:\/\/abinox-chr-clim.com\/index.php\/wp-json\/wp\/v2\/product\/110559","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/abinox-chr-clim.com\/index.php\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/abinox-chr-clim.com\/index.php\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/abinox-chr-clim.com\/index.php\/wp-json\/wp\/v2\/comments?post=110559"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/abinox-chr-clim.com\/index.php\/wp-json\/wp\/v2\/media\/105661"}],"wp:attachment":[{"href":"https:\/\/abinox-chr-clim.com\/index.php\/wp-json\/wp\/v2\/media?parent=110559"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/abinox-chr-clim.com\/index.php\/wp-json\/wp\/v2\/product_brand?post=110559"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/abinox-chr-clim.com\/index.php\/wp-json\/wp\/v2\/product_cat?post=110559"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/abinox-chr-clim.com\/index.php\/wp-json\/wp\/v2\/product_tag?post=110559"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}